{"id":83,"count":2,"description":"","link":"https:\/\/levenskrachtgemeente.nl\/en\/category\/kracht\/","name":"Power","slug":"kracht","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/categories\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/posts?categories=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}