{"id":79,"count":2,"description":"","link":"https:\/\/levenskrachtgemeente.nl\/en\/category\/volharding\/","name":"Persistence","slug":"volharding","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/categories\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/levenskrachtgemeente.nl\/en\/wp-json\/wp\/v2\/posts?categories=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}